{"id":21851,"date":"2022-02-02T18:35:52","date_gmt":"2022-02-02T23:35:52","guid":{"rendered":"https:\/\/profonanpe.org.pe\/?post_type=publicaciones&#038;p=21851"},"modified":"2026-04-20T09:36:02","modified_gmt":"2026-04-20T14:36:02","slug":"el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico","status":"publish","type":"publicaciones","link":"https:\/\/profonanpe.org.pe\/en\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/","title":{"rendered":"The Aguaje: Amazonian Superfood and the benefits of managing and conserving \u201caguajales\u201d for Amazonian regional development"},"parent":0,"template":"","ano-de-publicacion":[300],"class_list":["post-21851","publicaciones","type-publicaciones","status-publish","hentry","ano-de-publicacion-300"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico - Profonanpe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/profonanpe.org.pe\/en\/publications\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico - Profonanpe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/profonanpe.org.pe\/en\/publications\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/\" \/>\n<meta property=\"og:site_name\" content=\"Profonanpe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T14:36:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/profonanpe.org.pe\/wp-content\/uploads\/2020\/10\/Snippet-Profonanpe-v2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"524\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\\\/\",\"url\":\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\\\/\",\"name\":\"El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico - Profonanpe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#website\"},\"datePublished\":\"2022-02-02T23:35:52+00:00\",\"dateModified\":\"2026-04-20T14:36:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/profonanpe.org.pe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaciones\",\"item\":\"https:\\\/\\\/profonanpe.org.pe\\\/publicaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#website\",\"url\":\"https:\\\/\\\/profonanpe.org.pe\\\/\",\"name\":\"Profonanpe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/profonanpe.org.pe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#organization\",\"name\":\"Profonanpe\",\"url\":\"https:\\\/\\\/profonanpe.org.pe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/profonanpe.org.pe\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Snippet-Profonanpe-v2.jpg\",\"contentUrl\":\"https:\\\/\\\/profonanpe.org.pe\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Snippet-Profonanpe-v2.jpg\",\"width\":524,\"height\":274,\"caption\":\"Profonanpe\"},\"image\":{\"@id\":\"https:\\\/\\\/profonanpe.org.pe\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Aguaje: Amazonian Superfood and the benefits of managing and conserving \u201caguajales\u201d for Amazonian regional development","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/profonanpe.org.pe\/en\/publications\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/","og_locale":"en_US","og_type":"article","og_title":"El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico - Profonanpe","og_url":"https:\/\/profonanpe.org.pe\/en\/publications\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/","og_site_name":"Profonanpe","article_modified_time":"2026-04-20T14:36:02+00:00","og_image":[{"width":524,"height":274,"url":"https:\/\/profonanpe.org.pe\/wp-content\/uploads\/2020\/10\/Snippet-Profonanpe-v2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/profonanpe.org.pe\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/","url":"https:\/\/profonanpe.org.pe\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/","name":"The Aguaje: Amazonian Superfood and the benefits of managing and conserving \u201caguajales\u201d for Amazonian regional development","isPartOf":{"@id":"https:\/\/profonanpe.org.pe\/#website"},"datePublished":"2022-02-02T23:35:52+00:00","dateModified":"2026-04-20T14:36:02+00:00","breadcrumb":{"@id":"https:\/\/profonanpe.org.pe\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/profonanpe.org.pe\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/profonanpe.org.pe\/publicaciones\/el-aguaje-superalimento-amazonico-y-los-beneficios-del-manejo-y-conservacion-de-los-aguajales-para-el-desarrollo-regional-amazonico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/profonanpe.org.pe\/"},{"@type":"ListItem","position":2,"name":"Publicaciones","item":"https:\/\/profonanpe.org.pe\/publicaciones\/"},{"@type":"ListItem","position":3,"name":"El Aguaje: Superalimento amaz\u00f3nico y los beneficios del manejo y conservaci\u00f3n de los \u201caguajales\u201d para el desarrollo regional amaz\u00f3nico"}]},{"@type":"WebSite","@id":"https:\/\/profonanpe.org.pe\/#website","url":"https:\/\/profonanpe.org.pe\/","name":"Profonanpe","description":"","publisher":{"@id":"https:\/\/profonanpe.org.pe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/profonanpe.org.pe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/profonanpe.org.pe\/#organization","name":"Profonanpe","url":"https:\/\/profonanpe.org.pe\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/profonanpe.org.pe\/#\/schema\/logo\/image\/","url":"https:\/\/profonanpe.org.pe\/wp-content\/uploads\/2020\/10\/Snippet-Profonanpe-v2.jpg","contentUrl":"https:\/\/profonanpe.org.pe\/wp-content\/uploads\/2020\/10\/Snippet-Profonanpe-v2.jpg","width":524,"height":274,"caption":"Profonanpe"},"image":{"@id":"https:\/\/profonanpe.org.pe\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/profonanpe.org.pe\/en\/wp-json\/wp\/v2\/publicaciones\/21851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/profonanpe.org.pe\/en\/wp-json\/wp\/v2\/publicaciones"}],"about":[{"href":"https:\/\/profonanpe.org.pe\/en\/wp-json\/wp\/v2\/types\/publicaciones"}],"wp:attachment":[{"href":"https:\/\/profonanpe.org.pe\/en\/wp-json\/wp\/v2\/media?parent=21851"}],"wp:term":[{"taxonomy":"ano-de-publicacion","embeddable":true,"href":"https:\/\/profonanpe.org.pe\/en\/wp-json\/wp\/v2\/ano-de-publicacion?post=21851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}